{"id":11845,"date":"2025-12-10T10:51:52","date_gmt":"2025-12-10T10:51:52","guid":{"rendered":"https:\/\/artstella-elixirs-floraux.com\/?post_type=product&#038;p=11845"},"modified":"2026-03-02T09:59:03","modified_gmt":"2026-03-02T09:59:03","slug":"mood-essence-elixir-pour-lhumeur-30ml-bush","status":"publish","type":"product","link":"https:\/\/artstella-elixirs-floraux.com\/en\/product\/mood-essence-elixir-pour-lhumeur-30ml-bush\/","title":{"rendered":"Mood Essence \u00ab\u00a0Elixir pour l&rsquo;humeur\u00a0\u00bb 30ml Bush"},"content":{"rendered":"<p>Ce complexe peut \u00eatre utilis\u00e9e par toute personne qui \u00e9prouve des sentiments de solitude ou d&rsquo;isolement; des regrets; un manque de confiance; une faible estime de soi; des hauts et des bas \u00e9motionnels; qui se sent \u00e0 plat ou \u00e9prouve une inqui\u00e9tude excessive; un manque d&rsquo;int\u00e9r\u00eat ou l&rsquo;absence de joie de vivre dans sa vie.<\/p>\n<p>Ce complexe est compos\u00e9 des \u00e9lixirs suivants : Crowea, Dog Rose, Peach-Flowered Tea Tree, Pink Flannel Flower, Sturt Desert Rose, Tall Yellow Top, Waratah.<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9lixir \u00ab Mood \u00bb favorise l&rsquo;\u00e9quilibre \u00e9motionnel, la clart\u00e9, l&rsquo;optimisme et un sentiment renouvel\u00e9 de joie. Il a \u00e9t\u00e9 con\u00e7u pour traiter et aider \u00e0 soulager les diverses conditions que tant de personnes malheureusement vivent en ce moment.<\/p>","protected":false},"featured_media":11846,"template":"","meta":[],"product_brand":[],"product_cat":[122],"product_tag":[],"class_list":{"0":"post-11845","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-les-composes-du-bush-australien","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"etheme_brands":{"errors":{"invalid_taxonomy":["Invalid taxonomy."]},"error_data":[]},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":6054,"url":"https:\/\/artstella-elixirs-floraux.com\/en\/product\/elixir-ocean-n13-phi-15ml\/","url_meta":{"origin":11845,"position":0},"title":"ELIXIR OCEAN N\u00b013 PHI 15ML","author":"eveapprill","date":"9 March 2025","format":false,"excerpt":"Cet \u00e9lixir aide \u00e9motionnellement les personnes sensibles, facilement bless\u00e9es qui se trouvent invisibles au contact des autres. Il les aide \u00e0 se renforcer et \u00e0 devenir plus souples. Pour se sentir plus l\u00e9gitime et avancer plus surement.","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2051.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6056,"url":"https:\/\/artstella-elixirs-floraux.com\/en\/product\/elixir-ocean-n14-phi-15ml\/","url_meta":{"origin":11845,"position":1},"title":"ELIXIR OCEAN N\u00b014 PHI 15ML","author":"eveapprill","date":"9 March 2025","format":false,"excerpt":"L\u2019\u00e9lixir agit \u00e9nerg\u00e9tiquement pour lib\u00e9rer des blocages tr\u00e8s profond\u00e9ment ancr\u00e9s. Il nous lib\u00e8re int\u00e9rieurement des anciennes barri\u00e8res et sch\u00e9mas qui limitent l\u2019estime de soi. L\u2019\u00e9lixir agit fortement sur le cerveau, activant les h\u00e9misph\u00e8res c\u00e9r\u00e9braux et le lobe frontal.","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2052.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5220,"url":"https:\/\/artstella-elixirs-floraux.com\/en\/product\/beluga\/","url_meta":{"origin":11845,"position":2},"title":"Beluga","author":"eveapprill","date":"9 March 2025","format":false,"excerpt":"Cet \u00e9lixir nous rappelle la joie et la l\u00e9g\u00e8ret\u00e9 enfantine. Il nous apprend \u00e0 ne pas prendre la vie trop au s\u00e9rieux et \u00e0 rester enjou\u00e9","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image1501.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5510,"url":"https:\/\/artstella-elixirs-floraux.com\/en\/product\/beluga-2\/","url_meta":{"origin":11845,"position":3},"title":"BELUGA","author":"eveapprill","date":"9 March 2025","format":false,"excerpt":"BELUGA \u00a0- Wei\u00dfwal \u00a0\u00a0(Delphinapterus leucas) Cet \u00e9lixir nous rappelle la joie et la l\u00e9g\u00e8ret\u00e9 enfantine. Il nous apprend \u00e0 ne pas prendre la vie trop au s\u00e9rieux et \u00e0 rester enjou\u00e9. L\u2019\u00e9lixir aide \u00e9motionnellement les personnes qui ont souffert de blocages, de chocs ou d\u2019\u00e9motions n\u00e9gatives pendant la vie f\u0153tale\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image1750.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5165,"url":"https:\/\/artstella-elixirs-floraux.com\/en\/product\/poisson-ange-royal-15-ml-phi\/","url_meta":{"origin":11845,"position":4},"title":"POISSON ANGE ROYAL 15 ML PHI","author":"eveapprill","date":"9 March 2025","format":false,"excerpt":"Poisson ange-royal (Pygoplites diacanthus) Kaiserfisch Ce poisson vit au milieu du corail en groupe. Son \u00e9lixir favorise la communication et le sentiment d\u2019appartenance.","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2264,"url":"https:\/\/artstella-elixirs-floraux.com\/en\/product\/river-beauty-alaskan\/","url_meta":{"origin":11845,"position":5},"title":"River beauty Alaskan","author":"eveapprill","date":"9 March 2025","format":false,"excerpt":"River beauty. Epilobium latifolium An\u00e9antissement \u00e9motionnel ; d\u00e9pass\u00e9 par le chagrin et la tristesse, ou un sentiment intense de perte ;","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image577.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/product\/11845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":4,"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/product\/11845\/revisions"}],"predecessor-version":[{"id":11850,"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/product\/11845\/revisions\/11850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/media\/11846"}],"wp:attachment":[{"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/media?parent=11845"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/product_brand?post=11845"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/product_cat?post=11845"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/en\/wp-json\/wp\/v2\/product_tag?post=11845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}