{"id":3847,"date":"2025-03-09T13:17:04","date_gmt":"2025-03-09T13:17:04","guid":{"rendered":"https:\/\/artstella-elixirs-floraux.com\/product\/crabe-phi-15-ml\/"},"modified":"2025-04-23T12:38:38","modified_gmt":"2025-04-23T12:38:38","slug":"crabe-phi-15-ml","status":"publish","type":"product","link":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/crabe-phi-15-ml\/","title":{"rendered":"CRABE PHI 15 ML"},"content":{"rendered":"<p><span style=\"color: #008000;\"><strong>Crabe<\/strong><\/span><br \/>\n(Grapsus grapsus) Krebs L\u2019\u00e9lixir de crabe aide les personnes qui s\u2019isolent et se retirent de fa\u00e7on excessive dans la vie priv\u00e9e ainsi que celles qui sont trop prudentes \u00e0 s\u2019ouvrir. Il nous permet aussi de reconna\u00eetre le danger v\u00e9ritable et le moment o\u00f9 il est n\u00e9cessaire de se retirer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong><span style=\"color: #008000;\">Crabe<\/span><br \/>\n<\/strong>(Grapsus grapsus) Krebs L\u2019\u00e9lixir de crabe aide les personnes qui s\u2019isolent et se retirent de fa\u00e7on excessive dans la vie priv\u00e9e ainsi que celles qui sont trop prudentes \u00e0 s\u2019ouvrir.<\/p>\n","protected":false},"featured_media":3848,"template":"","meta":[],"product_brand":[],"product_cat":[99],"product_tag":[],"class_list":{"0":"post-3847","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-les-elixirs-de-la-mer","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"etheme_brands":{"errors":{"invalid_taxonomy":["Taxonomie non valide."]},"error_data":[]},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2801,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/crab-apple-phi-15ml\/","url_meta":{"origin":3847,"position":0},"title":"CRAB APPLE PHI 15ML","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"Crab Apple (Malus pumila) (Pommier sauvage)Soutient les processus de purification, quand nous nous sentons salis int\u00e9rieurement ou que nous avons peur d'\u00eatre contamin\u00e9s. Pour se d\u00e9barrasser des vieux sch\u00e9mas et trouver un nouvel ordonnancement de vie.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image333.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4088,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/arbol-de-mariposa-fleur-sylfos-15ml\/","url_meta":{"origin":3847,"position":1},"title":"ARBOL DE MARIPOSA FLEUR SYLFOS 15ML","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"ARBRE\u00a0 AUX PAPILLONS \/ ARBOL DE MARIPOSAS Butterfly-Bush\u00a0\u00a0\u00a0\u00a0Buddleja davidii Pour ceux qui ont besoin de faire un changement dans leur vie et qui reconnaissent avoir besoin d\u2019une aide spirituelle. Recommand\u00e9 pour les personnes qui n\u2019arrivent pas \u00e0 avancer \u00e0 cause de l\u2019orgueil ou qui r\u00e9agissent de fa\u00e7on n\u00e9gative face aux\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5220,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/beluga\/","url_meta":{"origin":3847,"position":2},"title":"Beluga","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"Cet \u00e9lixir nous rappelle la joie et la l\u00e9g\u00e8ret\u00e9 enfantine. Il nous apprend \u00e0 ne pas prendre la vie trop au s\u00e9rieux et \u00e0 rester enjou\u00e9","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image1501.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5510,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/beluga-2\/","url_meta":{"origin":3847,"position":3},"title":"BELUGA","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"BELUGA \u00a0- Wei\u00dfwal \u00a0\u00a0(Delphinapterus leucas) Cet \u00e9lixir nous rappelle la joie et la l\u00e9g\u00e8ret\u00e9 enfantine. Il nous apprend \u00e0 ne pas prendre la vie trop au s\u00e9rieux et \u00e0 rester enjou\u00e9. L\u2019\u00e9lixir aide \u00e9motionnellement les personnes qui ont souffert de blocages, de chocs ou d\u2019\u00e9motions n\u00e9gatives pendant la vie f\u0153tale\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image1750.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6207,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/elixir-ocean-n-24-phi-15ml\/","url_meta":{"origin":3847,"position":4},"title":"ELIXIR OCEAN N\u00b0 24 PHI 15ml","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"ELIXIR OCEAN N\u00b0 24\u00a0 aide les personnes qui manquent d\u2019orientation et se sentent perdus \u00e0 re-trouver une solidit\u00e9 int\u00e9rieure leur permettant de s\u2019ouvrir \u00e0 un partenariat dans une stabilit\u00e9 int\u00e9rieure. Il aidera \u00e9galement, au plan spirituel, \u00e0 pouvoir faire confiance en Dieu. Pour trouver un sens et du contenu \u00e0\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2198.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11845,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/mood-essence-elixir-pour-lhumeur-30ml-bush\/","url_meta":{"origin":3847,"position":5},"title":"Mood Essence \u00ab\u00a0Elixir pour l&rsquo;humeur\u00a0\u00bb 30ml Bush","author":"eveapprill","date":"10 d\u00e9cembre 2025","format":false,"excerpt":"L\u2019\u00e9lixir \u00ab Mood \u00bb favorise l'\u00e9quilibre \u00e9motionnel, la clart\u00e9, l'optimisme et un sentiment renouvel\u00e9 de joie. Il a \u00e9t\u00e9 con\u00e7u pour traiter et aider \u00e0 soulager les diverses conditions que tant de personnes malheureusement vivent en ce moment.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product\/3847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product\/3847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/media\/3848"}],"wp:attachment":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=3847"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product_brand?post=3847"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product_cat?post=3847"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product_tag?post=3847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}