{"id":6173,"date":"2025-03-09T13:53:33","date_gmt":"2025-03-09T13:53:33","guid":{"rendered":"https:\/\/artstella-elixirs-floraux.com\/product\/corona-del-inca-sylfos-15ml\/"},"modified":"2025-04-30T20:41:02","modified_gmt":"2025-04-30T20:41:02","slug":"corona-del-inca-sylfos-15ml","status":"publish","type":"product","link":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/corona-del-inca-sylfos-15ml\/","title":{"rendered":"CORONA DEL INCA SYLFOS 15ML"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"MsoNormal\" style=\"margin-bottom: .0001pt\">\u00a0<strong>CORONA DEL INCA \/<\/strong> <strong>Poinsettia<\/strong> Euphorbiapulcherrima Amour et Espoir<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: .0001pt\">Cet \u00e9lixir permet de d\u00e9passer les barri\u00e8res de l\u2019amour, pour pouvoir s\u2019ouvrir vers le prochain, vers l\u2019humanit\u00e9 enti\u00e8re, ce qui permet de trouver sa place dans l\u2019humanit\u00e9. Sera de grande utilit\u00e9 pour recomposer les relations interpersonnelles dans un groupe ou au sein d\u2019un couple.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"featured_media":6174,"template":"","meta":[],"product_brand":[],"product_cat":[139],"product_tag":[],"class_list":{"0":"post-6173","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-les-fleurs-andiness-upplementaires-compose","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"etheme_brands":{"errors":{"invalid_taxonomy":["Taxonomie non valide."]},"error_data":[]},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":4096,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/condor-el-chamaniques-15ml\/","url_meta":{"origin":6173,"position":0},"title":"CONDOR EL CHAMANIQUES 15ML","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"CONDOR\u00a0\u00a0 Le Roi Inca \u2013 Vision - Renaissance Le Condor cherche les plus hautes altitudes afin de communiquer avec les dieux.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image762.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3642,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/46-pushing-back-the-night-ltoe-15-ml\/","url_meta":{"origin":6173,"position":1},"title":"PUSHING BACK THE NIGHT LTOE 15 ML","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"Pushing Back the Night\u00a0 \/ Repousser la nuit Cet \u00e9lixir favorise un \u00e9tat d\u2019esprit o\u00f9 vision et lumi\u00e8re se confondent, permettant de prendre conscience que la vie est sacr\u00e9e. Son but est d\u2019aider \u00e0 gu\u00e9rir le destin de l\u2019humanit\u00e9.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/2b1ff100-6342-4cb5-a1c6-56a752173a69.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/2b1ff100-6342-4cb5-a1c6-56a752173a69.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/2b1ff100-6342-4cb5-a1c6-56a752173a69.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/2b1ff100-6342-4cb5-a1c6-56a752173a69.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3503,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/love-beyond-love-15-ml-ltoe\/","url_meta":{"origin":6173,"position":2},"title":"LOVE BEYOND LOVE 15 ML LTOE","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"Love beyond love\u00a0 \/ L'amour au-del\u00e0 de l'amour (Just me, Love\u2019s secret, Moon Child, Unconditional snuggles et White Beauty) Pour les enfants ou les adultes qui n\u2019ont pas \u00e9t\u00e9 aim\u00e9s pendant la grossesse et qui en souffrent.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/9261c17a-706e-4a8c-97df-eeda6dec5405.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/9261c17a-706e-4a8c-97df-eeda6dec5405.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/9261c17a-706e-4a8c-97df-eeda6dec5405.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/9261c17a-706e-4a8c-97df-eeda6dec5405.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3627,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/39-necklace-of-beauty-15-ml\/","url_meta":{"origin":6173,"position":3},"title":"NECKLACE OF BEAUTY 15 ML","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"Necklace of beauty \/ Collier de beaut\u00e9 : apporte une magnifique \u00e9nergie d'amour dans le chakra sup\u00e9rieur du c\u0153ur, nous permettant de nous sentir aim\u00e9, \u00e9lev\u00e9 et en paix.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/0c3a666b-f328-482a-86c7-cbea44b63d1e.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/0c3a666b-f328-482a-86c7-cbea44b63d1e.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/0c3a666b-f328-482a-86c7-cbea44b63d1e.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/0c3a666b-f328-482a-86c7-cbea44b63d1e.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6308,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/unconditional-love-ltoe15ml\/","url_meta":{"origin":6173,"position":4},"title":"UNCONDITIONAL LOVE LTOE15ML","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"Unconditional Love \u2013 Amour Inconditionnel L\u2019\u00e2me aspire \u00e0 se reconnecter \u00e0 notre source ultime, avec l\u2019Etre qui est au-del\u00e0 de notre compr\u00e9hension. Une \u00e9tape cl\u00e9 sur ce chemin vers ce que certains appellent le Divin est de l\u00e2cher les sch\u00e9mas restrictifs qui conditionnent l\u2019ouverture du c\u0153ur aux autres.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2242.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2242.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2242.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2242.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2242.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2242.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":5568,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/rose-reine-du-danemark-sylfos-15-ml\/","url_meta":{"origin":6173,"position":5},"title":"ROSE REINE DU DANEMARK SYLFOS 15 ML","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"ROSE KOENING VAN DAENMARK\u00a0 Rose Reine du Danemark Rosa alaba \u00a0 \u00a0 \u00a0 \u00a0 Permet un l\u00e2cher prise face aux blessures \u00e9motionnelles. Guide vers la possibilit\u00e9 de donner et de recevoir l\u2019Amour, lib\u00e9rant ainsi notre c\u0153ur. Equilibre les activit\u00e9s des h\u00e9misph\u00e8res droit et gauche\u00a0 du cerveau.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product\/6173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product\/6173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/media\/6174"}],"wp:attachment":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=6173"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product_brand?post=6173"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product_cat?post=6173"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product_tag?post=6173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}