{"id":6268,"date":"2025-03-09T13:55:15","date_gmt":"2025-03-09T13:55:15","guid":{"rendered":"https:\/\/artstella-elixirs-floraux.com\/product\/abutilon-sylfos-15ml\/"},"modified":"2025-06-08T12:56:06","modified_gmt":"2025-06-08T12:56:06","slug":"abutilon-sylfos-15ml","status":"publish","type":"product","link":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/abutilon-sylfos-15ml\/","title":{"rendered":"ABUTILON SYLFOS 15ML"},"content":{"rendered":"<p>Aide \u00e0 calmer les intr\u00e9pides, afin que cette dynamique ne produise pas de perturbations. Lorsqu&rsquo;il y a un ralentissement de la dynamique d\u00fb \u00e0 l&rsquo;ind\u00e9cision, aide \u00e0 la prise de d\u00e9cision<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong><sub>ABUTILON <\/sub><\/strong><em><sub>(Abutilon pictum) <strong>Compr\u00e9hension et Appr\u00e9ciation de l\u2019exp\u00e9rience<\/strong><\/sub><\/em><strong><\/strong><\/p>\n<p><sub>Permet l&rsquo;expression du chagrin. Active les souvenirs profonds. Am\u00e9liore la cr\u00e9ativit\u00e9. Nettoie le chagrin qui obscurcit nos racines originelles, permettant une meilleure compr\u00e9hension de notre v\u00e9ritable t\u00e2che dans la vie. <br \/><\/sub><\/p>\n","protected":false},"featured_media":6269,"template":"","meta":[],"product_brand":[],"product_cat":[139],"product_tag":[],"class_list":{"0":"post-6268","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-les-fleurs-andiness-upplementaires-compose","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"etheme_brands":{"errors":{"invalid_taxonomy":["Taxonomie non valide."]},"error_data":[]},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5694,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/fuchsia10-ml-deva\/","url_meta":{"origin":6268,"position":0},"title":"Fuchsia15 ml DEVA","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"Fuchsia Compr\u00e9hension des \u00e9motions enfouies. Catalyseur \u00e9motionnel favorisant l\u2019\u00e9mergence, la compr\u00e9hension et la r\u00e9solution des \u00e9motions li\u00e9es \u00e0 la col\u00e8re et au chagrin qui remontent souvent \u00e0 l\u2019enfance.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2401.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2264,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/river-beauty-alaskan\/","url_meta":{"origin":6268,"position":1},"title":"River beauty Alaskan","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"River beauty. Epilobium latifolium An\u00e9antissement \u00e9motionnel ; d\u00e9pass\u00e9 par le chagrin et la tristesse, ou un sentiment intense de perte ;","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image577.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4187,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/grieving-heart-wea-30-ml\/","url_meta":{"origin":6268,"position":2},"title":"GRIEVING HEART WEA 30 ML","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"Grieving Heart (chagrin de coeur) Aide \u00e0 se lib\u00e9rer de la souffrance \u00e9motionnelle et des larmes qui doivent \u00eatre vers\u00e9es pour pouvoir aller de l\u2019avant.","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image1012.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1963,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/wild-horse-foal-poulain-30ml-wea\/","url_meta":{"origin":6268,"position":3},"title":"WILD HORSE FOAL POULAIN 30ML WEA","author":"eveapprill","date":"27 mai 2025","format":false,"excerpt":"Wild Horse Foal (poulain sauvage) apporte le soutien n\u00e9cessaire pour embrasser et se lib\u00e9rer des larmes de chagrins non r\u00e9solus depuis l\u2019enfance. Favorise la sinc\u00e9rit\u00e9 et la douceur. Pour embrasser le c\u0153ur tendre et pur de l\u2019enfant en nous, encourageant la douceur et le sentiment d\u2019appartenance. Pour approfondir le ressenti\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/05\/foal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/05\/foal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/05\/foal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/05\/foal.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4005,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/bougainvillee-sylfos-15-ml\/","url_meta":{"origin":6268,"position":4},"title":"BOUGAINVILLEA \/ BOUGAINVILLEE SYLFOS","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"BOUGAINVILLEA Bougainvillea glabra Compr\u00e9hension et int\u00e9gration du pass\u00e9 ancestral, renaissance Pour prendre conscience et int\u00e9grer pleinement l\u2019h\u00e9ritage ancestral...","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6182,"url":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/produit\/men-homme-bush-australien-30ml\/","url_meta":{"origin":6268,"position":5},"title":"MEN &#8211; \u00ab\u00a0Homme\u00a0\u00bb Bush Australien 30ml","author":"eveapprill","date":"9 mars 2025","format":false,"excerpt":"MEN Pour les homes toujours sur la br\u00e8che, ce qui peut conduire \u00e0 de l\u2019impatience et de l\u2019irritabilit\u00e9. Pour ressentir et exprimer ses sentiments. \u00a0","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2185.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2185.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2185.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/artstella-elixirs-floraux.com\/wp-content\/uploads\/2025\/03\/wp-image2185.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product\/6268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product\/6268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/media\/6269"}],"wp:attachment":[{"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=6268"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product_brand?post=6268"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product_cat?post=6268"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/artstella-elixirs-floraux.com\/fr_fr\/wp-json\/wp\/v2\/product_tag?post=6268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}